{"id":8148,"date":"2015-04-25T22:31:45","date_gmt":"2015-04-25T22:31:45","guid":{"rendered":"http:\/\/www2.nasaacin.org\/index.php\/2015\/04\/25\/ante-la-carta-de-las-farc-a-santos-una-condicion-impostergable-desde-los-pueblos\/"},"modified":"2015-04-25T22:31:45","modified_gmt":"2015-04-25T22:31:45","slug":"ante-la-carta-de-las-farc-a-santos-una-condicion-impostergable-desde-los-pueblos","status":"publish","type":"post","link":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/2015\/04\/25\/ante-la-carta-de-las-farc-a-santos-una-condicion-impostergable-desde-los-pueblos\/","title":{"rendered":"Ante la carta de las Farc a Santos: Una condici\u00f3n impostergable desde los pueblos"},"content":{"rendered":"<div> \t<\/div>\n<div> \t<span style=\"font-size: 0.8em; line-height: 19.2000007629395px;\">Fotograf\u00eda de Jes\u00fas Abad Colorado<\/span><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tEn este contexto, las FARC reiteran su decisi\u00f3n de mantener una tregua unilateral y ahora, en la <a href=\"http:\/\/farc-ep.co\/?p=4450\" target=\"_blank\" rel=\"noopener noreferrer\">carta anexa dirigida a Juan Manuel Santos<\/a>, insisten en que se den a conocer verdades que han surgido gracias a las negociaciones de La Habana. Algunas de estas exigencias que expresan las FARC han sido planteadas desde comunidades, procesos e individuos de manera reiterada: De una parte, que asuma por fin su compromiso real con la historia y con el fin de la guerra y se defina.&nbsp;<\/div>\n<p>  <!--more-->  <\/p>\n<div> \t&nbsp;<\/div>\n<div> \tNo puede seguir el Presidente d\u00e1ndole la vuelta al mundo hablando de paz y cediendo cada vez ante las exigencias de quienes quieren perpetuar la guerra. Este es el momento de la verdad: \u00bfest\u00e1 Santos con la paz o con la guerra? No puede seguir jugando a dos bandas. De otra, le exigen hacer p\u00fablicos documentos esenciales: los archivos de Estado en relaci\u00f3n con la guerra y el documento redactado por la Comisi\u00f3n Hist\u00f3rica del Conflicto y sus V\u00edctimas. Pero adem\u00e1s, es indispensable que la estrategia paramilitar del r\u00e9gimen se conozca, para que pueda ser desmontada. Esta no es solamente una exigencia de las FARC. Es una necesidad, un imperativo impostergable de toda Colombia. Acuerdos de Paz insurgencia-estado con paramilitares equivale al establecimiento del terror permanente al servicio de la acumulaci\u00f3n privilegiada y mafiosa. Son verdades que debe conocer el pa\u00eds y es justo que sean expuestas y difundidas. Los hechos de la vereda La Esperanza en el que fueron emboscados soldados y fueron asesinados 11 militares deben investigarse y esclarecerse. Que se sepa qu\u00e9 pas\u00f3 y si las FARC asesinaron a soldados en condici\u00f3n de indefensi\u00f3n, que asuman su responsabilidad, as\u00ed como unos y otros deben asumir los cr\u00edmenes que han cometido una y otra vez contra poblaciones (y combatientes) impotentes. \u00bfCu\u00e1ntos padres y madres de ni\u00f1os y ni\u00f1as asesinados por \u201cvalientes combatientes\u201d de uno y otro lado cuyas muertes justifican o ignoran comandantes y gobernantes pueden sentir respeto por ustedes y confiar en sus palabras y acuerdos entre asesinos? Ac\u00e1 deber\u00eda ir la lista interminable y el dolor insufrible que ustedes han infringido y no asumen mientras no cesen en su masacrar acompa\u00f1ado de palabras mentidas de libertad y justicia y sus actos de terror. <a href=\"http:\/\/www.pueblosencamino.org\/index.php\/donde-estamos\/lectura-de-contexto\/1305-una-condicion-impostergable-desde-los-pueblos-frente-a-la-carta-de-las-farc-a-santos\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfDonde Estamos? Pueblos en Camino,<\/a><\/div>\n<div> \t&nbsp;<\/div>\n<div style=\"text-align: center;\"> \t<strong><span style=\"font-size:18px;\">Ante la <a href=\"http:\/\/farc-ep.co\/?p=4450\" target=\"_blank\" rel=\"noopener noreferrer\">Carta de las FARC a Santos<\/a>:&nbsp;<\/span><\/strong><\/div>\n<div style=\"text-align: center;\"> \t<strong><span style=\"font-size:18px;\">Una condici\u00f3n impostergable desde los pueblos<\/span><\/strong><\/div>\n<div style=\"text-align: center;\"> \tCon Fotograf\u00edas de <strong>Jes\u00fas Abad Colorado<\/strong><\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<img src=\"http:\/\/3.bp.blogspot.com\/_9__NE82fBxE\/StOOvrEfuBI\/AAAAAAAAABU\/oFRlNFK6v5c\/s320\/ImgArticulo_T1_60405_200939_164223.jpg\" style=\"font-size: 0.8em; line-height: 19.2000007629395px; margin: 5px; float: left;\" \/>Alcanzar acuerdos de paz para el cese definitivo y permanente del conflicto armado entre las FARC-EP y el Gobierno de Colombia requiere que los juegos y maniobras que se sirven de la guerra y de la negociaci\u00f3n para lograr objetivos estrat\u00e9gicos, no puedan servirse de la guerra y, adem\u00e1s, que las verdades vayan superando la propaganda y la manipulaci\u00f3n, elementos constitutivos de una guerra permanente.&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n<div> \tLa cultura institucionalizada en Colombia es, precisamente, la de la violencia y la maniobra con fines estrat\u00e9gicos. Cultura forjada por y desde el r\u00e9gimen y reproducida por opositores sometidos a la misma. De all\u00ed que, para entender los hechos, hay que ignorar una y otra vez lo inmediato y aparente, f\u00e1cilmente manipulado y manipulable y buscar las respuestas en quienes obtienen beneficios sea cual sea el acontecimiento (sin que esto quiera decir, ignorar responsabilidades, derechos y justicia). As\u00ed las cosas, de no desplazarse activamente la din\u00e1mica hacia dejar atr\u00e1s las acciones de terror y guerra y empezar a decir verdades, la desconfianza justa seguir\u00e1 creciendo, como es el caso actual, y con ello, los acuerdos que se logren, si es que no son impedidos de antemano por estos juegos patriarcales de guerra, no tendr\u00e1n credibilidad alguna: \u00bfqui\u00e9n puede creerle a maestros y magos en mentir, maniobrar y matar con discursos que se\u00f1alan al otro mientras se reclaman a s\u00ed mismos justos y v\u00edctimas sabiendo que no lo son?&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<img src=\"http:\/\/i.ytimg.com\/vi\/LkZsWIjMFgs\/maxresdefault.jpg\" style=\"height: 394px; width: 700px;\" \/><span style=\"font-size: 0.8em; line-height: 19.2000007629395px;\">Fotograf\u00eda de Jes\u00fas Abad Colorado<\/span><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tEl fin de esta guerra entre la insurgencia y el estado deber\u00eda obedecer a un mandato de toda Colombia, real pero reiteradamente negado y aprovechado: la gente no cree en los actores armados, no cree en la guerra, no cree en sus discursos y est\u00e1 empozada en sangre y l\u00e1grimas consecuencia de discursos que justifican y explican la guerra en beneficio de quienes son sus v\u00edctimas. En otras palabras, Colombia ya no quiere m\u00e1s ni cree sus mentiras y maniobras y sabe que ustedes, a bala y plomo hablan mientras sus palabras son para encubrir o promover terror. Siendo as\u00ed, que lleguen a un acuerdo, depende en gran medida de que escuchen y respeten a la gente: a Colombia.&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<img src=\"http:\/\/1.bp.blogspot.com\/-PMeEcFXrNe4\/Udhr0Vnci5I\/AAAAAAAAAto\/9yg_E0B-Lpk\/s1600\/Jes\u00fas+Abad+Colorado+2.jpg\" style=\"height: 890px; width: 600px;\" \/><\/div>\n<div> \t<span style=\"font-size: 0.8em; line-height: 19.2000007629395px;\">Fotograf\u00eda de Jes\u00fas Abad Colorado<\/span><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tEn este contexto, las FARC reiteran su decisi\u00f3n de mantener una tregua unilateral y ahora, en<a href=\"http:\/\/farc-ep.co\/?p=4450\" target=\"_blank\" rel=\"noopener noreferrer\"> la carta anexa dirigida a Juan Manuel Santos<\/a>, insisten en que se den a conocer verdades que han surgido gracias a las negociaciones de La Habana. Algunas de estas exigencias que expresan las FARC han sido planteadas desde comunidades, procesos e individuos de manera reiterada: De una parte, que asuma por fin su compromiso real con la historia y con el fin de la guerra y se defina. No puede seguir el Presidente d\u00e1ndole la vuelta al mundo hablando de paz y cediendo cada vez ante las exigencias de quienes quieren perpetuar la guerra. Este es el momento de la verdad: \u00bfest\u00e1 Santos con la paz o con la guerra? No puede seguir jugando a dos bandas. De otra, le exigen hacer p\u00fablicos documentos esenciales: los archivos de Estado en relaci\u00f3n con la guerra y el documento redactado por la Comisi\u00f3n Hist\u00f3rica del Conflicto y sus V\u00edctimas. Pero adem\u00e1s, es indispensable que la estrategia paramilitar del r\u00e9gimen se conozca, para que pueda ser desmontada. Esta no es solamente una exigencia de las FARC. Es una necesidad, un imperativo impostergable de toda Colombia. Acuerdos de Paz insurgencia-estado con paramilitares equivale al establecimiento del terror permanente al servicio de la acumulaci\u00f3n privilegiada y mafiosa. Son verdades que debe conocer el pa\u00eds y es justo que sean expuestas y difundidas. Los hechos de la vereda La Esperanza en el que fueron emboscados soldados y fueron asesinados 11 militares deben investigarse y esclarecerse. Que se sepa qu\u00e9 pas\u00f3 y si las FARC asesinaron a soldados en condici\u00f3n de indefensi\u00f3n, que asuman su responsabilidad, as\u00ed como unos y otros deben asumir los cr\u00edmenes que han cometido una y otra vez contra poblaciones (y combatientes) impotentes. \u00bfCu\u00e1ntos padres y madres de ni\u00f1os y ni\u00f1as asesinados por \u201cvalientes combatientes\u201d de uno y otro lado cuyas muertes justifican o ignoran comandantes y gobernantes pueden sentir respeto por ustedes y confiar en sus palabras y acuerdos entre asesinos? Ac\u00e1 deber\u00eda ir la lista interminable y el dolor insufrible que ustedes han infringido y no asumen mientras no cesen en su masacrar acompa\u00f1ado de palabras mentidas de libertad y justicia y sus actos de terror.&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<img src=\"http:\/\/www.universes-in-universe.de\/columna\/col34\/colorado2-2.jpg\" style=\"height: 479px; width: 700px;\" \/><span style=\"font-size: 0.8em; line-height: 19.2000007629395px;\">Fotograf\u00eda de Jes\u00fas Abad Colorado<\/span><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tLa gente hace mucho tiempo est\u00e1 cansada y con raz\u00f3n, del desangre y las mentiras en una guerra en la que 7 de cada 10 v\u00edctimas no han sido miembros de las fuerzas confrontadas. Ret\u00f3rica para la muerte y el terror que somete a un pueblo a no poder luchar por sus derechos y a no poder vivir. La guerra, venga de donde venga, le sirve al modelo de despojo y privilegio, tanto o m\u00e1s, en el caso de Colombia, que la paz del modelo. Para que el fin del conflicto armado entre insurgencia y estado y el cese al fuego definitivo y permanente entre las FARC y el gobierno abran espacios reales para <a href=\"http:\/\/www.pueblosencamino.org\/index.php\/asi-si\/resistencias-y-luchas-sociales02\/455-la-paz-de-los-pueblos-sin-duenos\" target=\"_blank\" rel=\"noopener noreferrer\">la paz de los pueblos sin due\u00f1os<\/a>, las voces, memorias, experiencias y exigencias de un pueblo deben sentirse y escucharse de manera cada vez m\u00e1s fuerte y clara y deben empezar a respetarse, porque, hasta ahora, no las respeta nadie que porte un arma o comande ej\u00e9rcitos o guerrillas. Esta es la condici\u00f3n para la paz. Tregua, cese definitivo de acciones agresivas, cese al fuego bilateral y apertura de espacios y mecanismos para que se sepan verdades y que las verdades reemplacen los trucos, las propagandas y las maniobras. No hay paz sin verdad y &nbsp;sin pueblos aut\u00f3nomos, as\u00ed como no hay guerra que los respete. Debe reconocer el gobierno y la insurgencia de las FARC que llegaron a un punto en las negociaciones que, planificado o no, les guste o no, les obliga a respetar a Colombia y a subordinar por lo menos los objetivos estrat\u00e9gicos m\u00e1s evidentes de intereses particulares, a derechos y exigencias colectivas como estos planteados. Que ustedes pierdan posiciones implica que las gana Colombia. De ello dependen los acuerdos y la credibilidad que merezcan. Sigan en su empe\u00f1o de ganarle a Colombia con las negociaciones y si ganan pasar\u00e1 exactamente eso:<strong> Pierde Colombia<\/strong><\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<img src=\"http:\/\/www.arcoiris.com.co\/wp-content\/uploads\/2014\/01\/361496_181747_1.jpg\" style=\"height: 383px; width: 700px;\" \/><\/div>\n<div> \t<span style=\"font-size: 0.8em; line-height: 19.2000007629395px;\">Fotograf\u00eda de Jes\u00fas Abad Colorado<\/span><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tPara transformar una cultura de mentiras y enga\u00f1os establecida para obtener beneficios y encubrir el terror, se requiere que este tema salga a la superficie y deje de ser ignorado. El d\u00eda en que sientan, que les hagamos colectivamente sentir verg\u00fcenza a los que mienten para ganar y conseguir y a nombre de las mas nobles de las causas persiguen los m\u00e1s repugnantes beneficios con el terror y la guerra, ese d\u00eda tendremos futuro y estaremos en camino hacia la paz. Ser\u00e1 el d\u00eda en que este modelo de la acumulaci\u00f3n basado en la mentira y el enga\u00f1o haya quedado supeditado al del respeto a la vida y al bienestar colectivo. Estamos muy lejos de ese d\u00eda. Ni siquiera podemos decir que vamos en esa direcci\u00f3n, pero, si a estas alturas de las negociaciones de La Habana, por lo menos, la guerra deja de ser un medio para embusteros y t\u00e1cticos y deja de serlo por exigencia y por respeto a un pa\u00eds despreciado que est\u00e1 absolutamente saciado de matones con discurso f\u00e1cil; si eso sucede, habr\u00e1 una posibilidad de que los acuerdos se logren y que no sean letra muerta que nadie crea y todos abusen. En este contexto es bienvenida esta carta de las FARC-EP y sus exigencias respaldadas por la decisi\u00f3n de mantener el cese al fuego unilateral. El gobierno debe entregar los documentos, cumplir con lo acordado y responder al cese al fuego con cese al fuego y fin de acciones ofensivas. No es por las FARC ni por el R\u00e9gimen. Es por Colombia, la Colombia de los pueblos de la que se han servido y se sirven para acceder, acrecentar o usurpar un bot\u00edn desangrando.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<span style=\"font-size:14px;\"><a href=\"http:\/\/www.pueblosencamino.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Pueblos en Camino&nbsp;<\/strong><\/a><\/span><\/div>\n<div> \tcon <strong>Fotograf\u00edas de Jes\u00fas Abad Colorado<\/strong><\/div>\n<div> \tAbril 25 de 2015<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n<div style=\"text-align: center;\"> \t<a href=\"http:\/\/farc-ep.co\/?p=4450\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"font-size:18px;\"><strong>Carta abierta de las FARC-EP al Presidente Santos<\/strong><\/span><\/a><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tEn el discurso de instalaci\u00f3n de la \u00faltima sesi\u00f3n del Consejo Nacional de Paz el se\u00f1or Presidente Santos manifest\u00f3 que por los hechos acaecidos el 14 de este mes en la vereda La Esperanza, municipio de Buenos Aires, Cauca, la pelota queda del lado de las FARC. Esto seguramente, refiri\u00e9ndose a que los comandantes guerrilleros se deben manifestar y actuar. Eso suponemos.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \tA este respecto fuimos claros al manifestar con motivo de la terminaci\u00f3n del ciclo 35 de las conversaciones de La Habana, que lo acontecido hab\u00eda sido un tragedia. &nbsp;\u201cY lo fue (lo afirmamos), porque la guerra es una enorme tragedia. En nuestra patria una tragedia de m\u00e1s de medio siglo. Precisamente por esto nos encontramos en La Habana\u201d. Y pusimos de presente de manera serena tres interrogantes: \u201c\u00bfQu\u00e9 sucedi\u00f3? \u00bfPor qu\u00e9 sucedi\u00f3? \u00bfC\u00f3mo sucedieron los hechos del 14?\u201d (Leer comunicado fin de ciclo 35) Esto con la intenci\u00f3n de manifestar que situaciones de guerra de la naturaleza que se dieron, hay que evitarlas a toda costa. Por eso a rengl\u00f3n seguido insistimos en reiterar la decisi\u00f3n de mantener el cese unilateral e indefinido de fuegos y hostilidades. Ya el pa\u00eds pudo constatar los beneficios de esa iniciativa nuestra, que para desgracia de la naci\u00f3n, fue recibida por algunos como \u201cuna rosa llena de espinas\u201d. Frase que desde un comienzo nos hizo entender que cualquier situaci\u00f3n cr\u00edtica de guerra que se pudiera dar en el camino, habr\u00eda de ser cobrada sin consideraciones de tiempo, modo y lugar. Sin embargo, seguimos sosteniendo la decisi\u00f3n pol\u00edtica-militar ya tomada. Pero en el l\u00f3gico entendimiento de que suspendido unilateralmente el fuego sin haberse solucionado a\u00fan el conflicto, se mantiene el natural derecho a la leg\u00edtima defensa. Al que est\u00e1 quieto hay que dejarlo quieto.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<img src=\"http:\/\/www.equidadeparaainfancia.org\/news\/octubre2011_1_files\/Contra el olvido Colombia Jesus Abad Colorado(1).jpg\" style=\"height: 815px; width: 700px;\" \/><span style=\"font-size: 0.8em; line-height: 19.2000007629395px;\">Jes\u00fas Abad Colorado<\/span><\/div>\n<div> \t&nbsp;<\/div>\n<div> \tBien ha anotado el Presidente Santos que \u201ces f\u00e1cil, muy f\u00e1cil, seguir hablando de guerra sentados en un escritorio o desde las trincheras de las redes sociales\u201d. Magn\u00edfica frase para ser tenida en cuenta cuando cualquier contratiempo que se presenta en el magno proyecto de la paz lleva a los enemigos agazapados y no agazapados de la reconciliaci\u00f3n, y a los sabios de \u00faltima hora en temas desconocidos para ellos, a rasgarse las vestiduras y a pedir que se mantengan sus comodidades a precio de litros de sangre ajena.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \tLas FARC-EP han sido claras al manifestar que la paz es un imperativo. Y que est\u00e1 en La Habana para cumplir con lo acordado con el gobierno el 26 de agosto de 2012. Su contenido es claro. Est\u00e1 al alcance de quien lo quiera conocer o repasar en los medios electr\u00f3nicos de comunicaci\u00f3n social. Y lo ponemos de presente porque comentaristas de oficio y varios bur\u00f3cratas, m\u00e1s afanados en agregar tiempo a su carrera hacia la jubilaci\u00f3n que en buscarle soluciones al conflicto, pontifican teniendo en cuenta su propio parecer sin ni siquiera evaluar lo sucedido en nuestra patria en los \u00faltimos sesenta a\u00f1os.&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n<div> \tEl proceso de paz hay que sacarlo al otro lado. Y r\u00e1pido. Sin recurrir a artilugios ma\u00f1osos y sin dilaciones injustificadas. El <a href=\"http:\/\/www.pazfarc-ep.org\/index.php\/acuerdos\/agenda-habana\" target=\"_blank\" rel=\"noopener noreferrer\">Acuerdo General para la Terminaci\u00f3n del Conflicto<\/a> es claro. En la Agenda se encuentran los instrumentos requeridos para llegar a la meta deseada. Ya que el bal\u00f3n est\u00e1 de nuestro lado, al decir del doctor Santos, se propone que aceleremos el proceso en el entendido s\u00ed, de que hay tiempos que no se pueden obviar. La consecuci\u00f3n de la paz no se logra con cron\u00f3metro en la mano, sino evacuando temas. Si de celeridad se trata, desde el ciclo 34 de conversaciones tenemos todas las propuestas referidas a v\u00edctimas sobre la mesa. &nbsp;Dicho esto, consideramos entonces que se deben adelantar algunos pasos que precipiten la terminaci\u00f3n del conflicto, para lo cual hay que dejar la subjetividad a un lado y ser pr\u00e1cticos.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<span style=\"font-size:14px;\"><strong>1- <\/strong><\/span>Le sugerimos al se\u00f1or Presidente de manera comedida, que el papel que viene asumiendo de activista de la paz y hacedor de la guerra corresponda m\u00e1s a su deseo de allanar el camino hacia una soluci\u00f3n posible de reconciliaci\u00f3n y menos a su necesidad de encenderle una vela a dios y otra al diablo. La pol\u00edtica local no debe alterar su ruta. Reconocemos que viene siendo azuzado (para emplear un t\u00e9rmino ya utilizado por nosotros) y retado desde columnas de opini\u00f3n, micr\u00f3fonos, salones sociales, escenarios pol\u00edticos y a\u00fan desde oficinas p\u00fablicas como la Vicepresidencia, desde donde se han atrevido a indicarle c\u00f3mo debe proceder. Es indispensable el mantenimiento de su serenidad.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<span style=\"font-size:14px;\"><strong>2- <\/strong><\/span>No hemos logrado entender por qu\u00e9 en La Mesa se dilatan o posponen decisiones que se han debido evacuar hace meses. Exigimos apresurar la marcha cuando se trata de asuntos de total obviedad. Desde que pusimos a consideraci\u00f3n la creaci\u00f3n de la <a href=\"http:\/\/www.pazfarc-ep.org\/index.php\/acuerdos\/informe-comision-historica\" target=\"_blank\" rel=\"noopener noreferrer\">Comisi\u00f3n Hist\u00f3rica del Conflicto y sus V\u00edctimas<\/a> hasta la fecha de su integraci\u00f3n, transcurri\u00f3 un a\u00f1o y tres meses. Y una vez entregado el informe, ha sido imposible darle tr\u00e1mite a sus conclusiones. El desgaste para lograr algo tan importante para el pa\u00eds y para el fin del conflicto, es inexplicable. Mucho m\u00e1s cuando expresidentes, el propio Jefe de Estado y quienes saben de historia de Colombia, reconocen que el conflicto se ha extendido por m\u00e1s de cincuenta a\u00f1os. Lo afirman y lo reiteran.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \tNo existe quien conociendo los informes de los comisionados -todos ellos venidos de procedencias dispares y de origen ideol\u00f3gicos contrapuestos-, no concluya que se da una responsabilidad del Estado por acci\u00f3n o por omisi\u00f3n, por la tragedia surgida hace d\u00e9cadas y que a\u00fan persiste. De all\u00ed que se hable de un n\u00famero significativo de victimarios procedentes de sectores diversos de la sociedad colombiana.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>As\u00ed las cosas proponemos al pa\u00eds:<\/strong><\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>a)<\/strong> Que se difunda masivamente el informe aludido. Imperante esta necesidad. Urgente. Debe enviarse a todos los rincones del pa\u00eds para su estudio y consideraci\u00f3n. A las universidades, colegios, normales, para que as\u00ed se contrarreste el hecho de que el pa\u00eds retir\u00f3 de su pensum de formaci\u00f3n acad\u00e9mica la historia de Colombia. Si no se conoce lo que ocurri\u00f3 en la patria en los \u00faltimos cincuenta o sesenta a\u00f1os, no se puede crear una conciencia y una cultura de la paz.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>b)<\/strong> Que el se\u00f1or Presidente conozca de manera detallada dicho documento denominado Contribuci\u00f3n al Entendimiento del Conflicto Armado en Colombia, (Comisi\u00f3n Hist\u00f3rica del Conflicto y sus V\u00edctimas), de febrero de 2015, e invite a su gabinete ministerial y funcionarios con capacidad de decisi\u00f3n a que se ocupen de su lectura y estudio.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>c)<\/strong> La integraci\u00f3n inmediata por la Mesa de una comisi\u00f3n de evaluaci\u00f3n de los resultados del informe y del estudio de los alcances para la paz, de la responsabilidad del Estado. Urge hacerlo para establecer precisamente responsabilidades jur\u00eddico-pol\u00edticas derivadas de su fundado contenido.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>d) <\/strong>La integraci\u00f3n inmediata de una comisi\u00f3n que conduzca al cumplimiento del subpunto 7 del punto 3 de la Agenda sobre terminaci\u00f3n del conflicto que dice as\u00ed: \u201c7. En el marco de lo establecido en el Punto 5 (V\u00edctimas) de este acuerdo se esclarecer\u00e1, entre otros, el fen\u00f3meno del paramilitarismo\u201d. La comisi\u00f3n que se cree para informar sobre el fen\u00f3meno del paramilitarismo debe ser integrada en la pr\u00f3xima ronda sin dilaci\u00f3n alguna.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>e)<\/strong> No se ha dado un proceso de paz en el mundo en el que no se haya conocido la verdad de lo ocurrido antes de la firma del acuerdo final, para lo cual, sin excepci\u00f3n que se conozca, se han abierto previamente los archivos de los diversos reg\u00edmenes. Por esto, pensando en las v\u00edctimas y en el derecho nacional e individual a la verdad, solicitaremos todos los d\u00edas y seguiremos insistiendo cada vez que nos encontremos con los plenipotenciarios del gobierno, en que se abran los archivos. Se deben dar a conocer las actas de los consejos de ministros que desde los a\u00f1os veinte del siglo pasado se guardan en secreto como si la historia fuera necesaria taparla para que no se juzgue. Que se abran los archivos de la polic\u00eda secreta, de los agentes de inteligencia del Estado (SIC, DAS, fuerza p\u00fablica en general, Ministerio de Guerra, hoy de Defensa, en lo relacionado al conflicto interno, y de Gobierno, hoy del Interior). \u00a1Que se abran los archivos! Le pedimos a los plenipotenciarios del gobierno y al Presidente Santos que en momentos en que buscamos conjuntamente la paz, no le tengan temor a la verdad. Que se abran los archivos.<\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<strong>SECRETARIADO DEL ESTADO MAYOR CENTRAL DE LAS FARC-EP<\/strong><\/div>\n<div> \tAbril 24 de 2015<\/div>\n<div> \t<a href=\"http:\/\/farc-ep.co\/?p=4450\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/farc-ep.co\/?p=4450<\/a><\/div>\n<div> \t&nbsp;<\/div>\n<div> \t<a href=\"http:\/\/www.pueblosencamino.org\/index.php\/donde-estamos\/lectura-de-contexto\/1305-una-condicion-impostergable-desde-los-pueblos-frente-a-la-carta-de-las-farc-a-santos\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.pueblosencamino.org\/index.php\/donde-estamos\/lectura-de-contexto\/1305-una-condicion-impostergable-desde-los-pueblos-frente-a-la-carta-de-las-farc-a-santos<\/a><\/div>\n<div> \t&nbsp;<\/div>\n<div> \t&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fotograf\u00eda de Jes\u00fas Abad Colorado &nbsp; En este contexto, las FARC reiteran su decisi\u00f3n de mantener una tregua unilateral y ahora, en la carta anexa dirigida a Juan Manuel Santos, insisten en [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[60],"tags":[],"_links":{"self":[{"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/posts\/8148"}],"collection":[{"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/comments?post=8148"}],"version-history":[{"count":0,"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/posts\/8148\/revisions"}],"wp:attachment":[{"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/media?parent=8148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/categories?post=8148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tejidohistorico.afrodescendientes.com\/index.php\/wp-json\/wp\/v2\/tags?post=8148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}